{"id":4815,"date":"2019-03-18T09:00:33","date_gmt":"2019-03-18T12:00:33","guid":{"rendered":"https:\/\/www.mobly.com.br\/blog\/?p=4815"},"modified":"2019-04-16T08:55:49","modified_gmt":"2019-04-16T11:55:49","slug":"top-3-tendencias-outono-2019","status":"publish","type":"post","link":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/","title":{"rendered":"Top 3 tend\u00eancias para o Outono 2019"},"content":{"rendered":"<div id=\"attachment_4816\" style=\"width: 798px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4816\" class=\"size-full wp-image-4816\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg\" alt=\"Tend\u00eancias de outono - Sala de estar\" width=\"788\" height=\"526\" srcset=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg 788w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre-300x200.jpg 300w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre-768x513.jpg 768w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><p id=\"caption-attachment-4816\" class=\"wp-caption-text\">Que tal come\u00e7ar a deixar a casa mais quentinha?<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>O outono \u00e9 sempre igual&#8230; Mas essa regra n\u00e3o se aplica na decora\u00e7\u00e3o! A cada ano, e em cada esta\u00e7\u00e3o, novas tend\u00eancias surgem \u2013 n\u00e3o s\u00f3 nas passarelas, mas tamb\u00e9m dentro dos lares. Afinal, moda e decora\u00e7\u00e3o caminham juntas.<\/p>\n<p>Para criar ambientes inspiradores, mas tamb\u00e9m acolhedores, a dica \u00e9 focar nas novidades, mas adaptando cada uma delas para a sua realidade. E o outono \u00e9 o per\u00edodo perfeito para criar cen\u00e1rios amenos, porque transita entre o calor do ver\u00e3o e o frio do inverno \u2013 e a\u00ed fica a deixa para se jogar, misturar e arriscar.<\/p>\n<p>Preparado para um <em>upgrade<\/em> outonal? Se liga nas dicas!<\/p>\n<p><strong>Veja tamb\u00e9m:<\/strong>\u00a0<a href=\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/cores-tendencia-2019-sala-de-estar\/\" target=\"_blank\" rel=\"noopener\">Arrase na decora\u00e7\u00e3o com as combina\u00e7\u00f5es de cores que ser\u00e3o tend\u00eancia em 2019<\/a>.<\/p>\n<h2><strong>Tapetes por todos os lados<\/strong><\/h2>\n<p>Que tapetes s\u00e3o pe\u00e7as-chaves para a decora\u00e7\u00e3o, isso todo mundo sabe. Voc\u00ea pode at\u00e9 estar pensando o porqu\u00ea dele estar aqui, sendo que \u00e9 um item t\u00e3o essencial&#8230; Mas, sabia que \u00e9 poss\u00edvel utiliz\u00e1-lo fora do contexto comum?<\/p>\n<p>Sim! Eles est\u00e3o saindo do ch\u00e3o e indo para as paredes, como verdadeiras obras de arte. Funcionam muito bem como uma alternativa para os <a href=\"https:\/\/www.mobly.com.br\/blog\/dicas\/como-usar-papel-de-parede\/\" target=\"_blank\" rel=\"noopener\">pap\u00e9is de parede<\/a>, cabeceiras de cama, acima do sof\u00e1, rack e onde mais a sua criatividade permitir. Eles n\u00e3o servem apenas para decorar, mas tamb\u00e9m para aquecer, colorir ou demarcar o espa\u00e7o. \u00c9 muita autenticidade!<\/p>\n<div id=\"attachment_4818\" style=\"width: 798px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4818\" class=\"size-full wp-image-4818\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tapetes-na-parede.jpg\" alt=\"Tend\u00eancias de outono - Tapetes na parede\" width=\"788\" height=\"526\" srcset=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tapetes-na-parede.jpg 788w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tapetes-na-parede-300x200.jpg 300w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tapetes-na-parede-768x513.jpg 768w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><p id=\"caption-attachment-4818\" class=\"wp-caption-text\">Uma forma de uso alternativo para o tapete \u00e9 coloc\u00e1-lo na parede.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Se voc\u00ea acha que n\u00e3o vai se adaptar \u00e0 ideia, outra maneira de us\u00e1-los \u00e9 com sobreposi\u00e7\u00e3o \u2013 um em cima do outro, brincando com texturas, tamanhos e cores. Mas, assim como nas roupas, \u00e9 necess\u00e1rio que as pe\u00e7as conversem entre si, para ter um resultado harm\u00f4nico. A tend\u00eancia est\u00e1 ligada ao contempor\u00e2neo, mas pode ser explorado em outros estilos de decor.<\/p>\n<div id=\"attachment_4822\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4822\" class=\"size-full wp-image-4822\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-sobreposicao-de-tapetes.jpg\" alt=\"Tend\u00eancias de Outono - Tapetes sobrepostos\" width=\"1024\" height=\"1071\" srcset=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-sobreposicao-de-tapetes.jpg 1024w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-sobreposicao-de-tapetes-287x300.jpg 287w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-sobreposicao-de-tapetes-768x803.jpg 768w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-sobreposicao-de-tapetes-979x1024.jpg 979w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-4822\" class=\"wp-caption-text\">Aconchego em dobro com o uso de dois tapetes.<\/p><\/div>\n<p>Inclusive, temos um conte\u00fado aqui no blog dando dicas de como combinar <a href=\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/tapetes\/\" target=\"_blank\" rel=\"noopener\">tapetes<\/a> sobrepostos em cada ambiente.<\/p>\n<h2><strong>Mix and match<\/strong><\/h2>\n<p>Chegou a vez da mistura de estampas! Falando assim, parece uma miss\u00e3o dif\u00edcil&#8230; Mas se voc\u00ea usar estampas com padr\u00f5es semelhantes \u00e9 poss\u00edvel garantir uma apar\u00eancia equilibrada e sem exageros. \u00c9 poss\u00edvel brincar com os pap\u00e9is de parede, tapetes, almofadas, mantas, toalhas de mesa&#8230; E por ai vai.<\/p>\n<p>H\u00e1 duas formas mais simples de fazer isso acontecer: com o uso de cores parecidas, dentro da mesma paleta ou alternando apenas o tom; ou quando os dois (ou mais) elementos seguem o mesmo tema \u2013 como listras com listras, florais com florais, animal print com animal print. Assim, fica mais f\u00e1cil ter um padr\u00e3o e, consequentemente, mais harmonia.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_4821\" style=\"width: 375px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4821\" class=\"wp-image-4821\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match2.jpg\" alt=\"Tend\u00eancias de Outono - Mix de estampas\" width=\"365\" height=\"243\" srcset=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match2.jpg 1024w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match2-300x200.jpg 300w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match2-768x513.jpg 768w\" sizes=\"auto, (max-width: 365px) 100vw, 365px\" \/><p id=\"caption-attachment-4821\" class=\"wp-caption-text\">Decor despojado que brinca com o uso de estampas misturadas&#8230;<\/p><\/div>\n<div id=\"attachment_4817\" style=\"width: 375px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4817\" class=\"wp-image-4817\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match1.jpg\" alt=\"Tend\u00eancias de Outono - Mix de estampas\" width=\"365\" height=\"243\" srcset=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match1.jpg 1024w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match1-300x200.jpg 300w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-mix-and-match1-768x512.jpg 768w\" sizes=\"auto, (max-width: 365px) 100vw, 365px\" \/><p id=\"caption-attachment-4817\" class=\"wp-caption-text\">&#8230; resultando em um mix que deu match.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><em>B\u00f4nus:<\/em> o xadrez nunca sai de moda e, mais uma vez, est\u00e1 mega em alta nesse outono!<\/p>\n<div id=\"metaslider-id-4842\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-27-0 metaslider metaslider-flex metaslider-4842 ml-slider slider-sku-padrao ml-slider-lightbox-1-12-0 lightbox-disabled\">\n    <div id=\"metaslider_container_4842\">\n        <div id=\"metaslider_4842\" class=\"flexslider\">\n            <ul aria-live=\"polite\" class=\"slides\">\n                <li style=\"display: none; width: 100%;\" class=\"slide-4850 ms-image\"><a href=\"https:\/\/www.mobly.com.br\/almofada-campestre-bege-e-amarela-565937.html\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/almofada-campestre-bege-e-amarela-565937-240x240.jpg\" height=\"240\" width=\"240\" alt=\"\" class=\"slider-4842 slide-4850\" title=\"almofada-campestre-bege-e-amarela-565937\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Almofada Campestre Bege e Amarela\n<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4849 ms-image\"><a href=\"https:\/\/www.mobly.com.br\/abajur-chevron-cinza-e-branco-com-base-verde-menta-553892.html\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/abajur-chevron-cinza-e-branco-com-base-verde-menta-553892-240x240.jpg\" height=\"240\" width=\"240\" alt=\"\" class=\"slider-4842 slide-4849\" title=\"abajur-chevron-cinza-e-branco-com-base-verde-menta-553892\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Abajur Chevron Cinza E Branco Com Base Verde Menta\n<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4853 ms-image\"><a href=\"https:\/\/www.mobly.com.br\/placa-decorativa-20x29-triangles-260987.html#a=3|p=19|pn=1|t=Categoria|c=339|b=1|s=0\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/placa-decorativa-20x29-triangles-260987-240x240.jpg\" height=\"240\" width=\"240\" alt=\"\" class=\"slider-4842 slide-4853\" title=\"placa-decorativa-20x29-triangles-260987\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Placa Decorativa 20X29 Triangles\n<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4852 ms-image\"><a href=\"https:\/\/www.mobly.com.br\/papel-de-parede-adesivo-chevron-verde-degrade-290-x-50-cm-583888.html\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/papel-de-parede-adesivo-chevron-verde-degrade-290-x-50-cm-583888-240x240.jpg\" height=\"240\" width=\"240\" alt=\"\" class=\"slider-4842 slide-4852\" title=\"papel-de-parede-adesivo-chevron-verde-degrade-290-x-50-cm-583888\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Papel de Parede Adesivo Chevron Verde Degrade 290 x 50 cm\n<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4851 ms-image\"><a href=\"https:\/\/www.mobly.com.br\/almofada-oca-ondas-350880.html\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/almofada-oca-ondas-350880-240x240.jpg\" height=\"240\" width=\"240\" alt=\"\" class=\"slider-4842 slide-4851\" title=\"almofada-oca-ondas-350880\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Almofada - Oca ondas\n<\/div><\/div><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\n<h2><strong>Tons terrosos is the new black<\/strong><\/h2>\n<p>De repente, os tons terrosos parecem mais interessantes, n\u00e3o \u00e9 mesmo? Eles t\u00eam sido falados (e utilizados) cada vez mais. Chegaram de mansinho, invadiram o universo da decora\u00e7\u00e3o e conquistaram muitos adeptos.<\/p>\n<p>Foi uma tend\u00eancia absoluta em 2017, esteve em todos os lugares em 2018, continua sendo neste ano e promete ser nos pr\u00f3ximos! Entendeu o porqu\u00ea da compara\u00e7\u00e3o com o preto? As deriva\u00e7\u00f5es do vermelho, como o bord\u00f4, s\u00e3o grandes apostas para essa esta\u00e7\u00e3o.<\/p>\n<div id=\"attachment_4819\" style=\"width: 317px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4819\" class=\"wp-image-4819\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo.jpg\" alt=\"Tend\u00eancias de Outono - Tons terrosos: bord\u00f4\" width=\"307\" height=\"314\" srcset=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo.jpg 1024w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo-294x300.jpg 294w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo-768x784.jpg 768w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo-1003x1024.jpg 1003w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><p id=\"caption-attachment-4819\" class=\"wp-caption-text\">O bord\u00f4 pode ser utilizado tanto nos m\u00f3veis&#8230;<\/p><\/div>\n<div id=\"attachment_4820\" style=\"width: 463px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4820\" class=\"wp-image-4820\" src=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo2.jpg\" alt=\"Tend\u00eancias de outono - Tons terrosos: bord\u00f4\" width=\"453\" height=\"317\" srcset=\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo2.jpg 1024w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo2-300x210.jpg 300w, https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-tons-terrosos-bordo2-768x537.jpg 768w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><p id=\"caption-attachment-4820\" class=\"wp-caption-text\">&#8230; como nas paredes!<\/p><\/div>\n<button class=\"simplefavorite-button has-count loading\" data-postid=\"4815\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"2\" style=\"\">Carregando...<span class=\"sf-icon-spinner-wrapper\"><i class=\"sf-icon-spinner\"><\/i><\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>&nbsp; O outono \u00e9 sempre igual&#8230; Mas essa regra n\u00e3o se aplica na decora\u00e7\u00e3o! A cada ano, e em cada esta\u00e7\u00e3o, novas tend\u00eancias surgem \u2013 n\u00e3o s\u00f3 nas passarelas, mas tamb\u00e9m dentro dos lares. Afinal, moda e decora\u00e7\u00e3o caminham juntas. Para criar ambientes inspiradores, mas tamb\u00e9m acolhedores, a dica \u00e9 focar nas novidades, mas adaptando cada uma delas para a sua realidade. E o outono \u00e9 o per\u00edodo perfeito para criar cen\u00e1rios amenos, porque transita entre o calor do ver\u00e3o e o frio do inverno \u2013 e a\u00ed fica a deixa para se jogar, misturar e arriscar. Preparado para um upgrade outonal? Se liga nas dicas! Veja tamb\u00e9m:\u00a0Arrase na decora\u00e7\u00e3o com as combina\u00e7\u00f5es de cores que ser\u00e3o tend\u00eancia em 2019. Tapetes por todos os lados Que tapetes s\u00e3o pe\u00e7as-chaves para a decora\u00e7\u00e3o, isso todo mundo sabe. Voc\u00ea pode at\u00e9 estar pensando o porqu\u00ea dele estar aqui, sendo que \u00e9 um item t\u00e3o essencial&#8230; Mas, sabia que \u00e9 poss\u00edvel utiliz\u00e1-lo fora do contexto comum? Sim! Eles est\u00e3o saindo do ch\u00e3o e indo para as paredes, como verdadeiras obras de arte. Funcionam muito bem como uma alternativa para os pap\u00e9is de parede, cabeceiras de cama, acima do sof\u00e1, rack e onde mais [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":4816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"extendify_custom_stylesheet":"","_mi_skip_tracking":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11],"tags":[15,104,29],"class_list":["post-4815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiracoes","tag-dicas","tag-outono","tag-tendencias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top 3 tend\u00eancias para o Outono 2019 | Blog da Mobly<\/title>\n<meta name=\"description\" content=\"Quer renovar a casa para a chegada da pr\u00f3xima esta\u00e7\u00e3o? A gente fez um estudo e reuniu as principais tend\u00eancias para o outono.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 3 tend\u00eancias para o Outono 2019 | Blog da Mobly\" \/>\n<meta property=\"og:description\" content=\"Quer renovar a casa para a chegada da pr\u00f3xima esta\u00e7\u00e3o? A gente fez um estudo e reuniu as principais tend\u00eancias para o outono.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Mobly\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-18T12:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-16T11:55:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.mobly.com.br\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"788\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ingrid Vilas Boas Morales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ingrid Vilas Boas Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/\",\"url\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/\",\"name\":\"Top 3 tend\u00eancias para o Outono 2019 | Blog da Mobly\",\"isPartOf\":{\"@id\":\"https:\/\/www.mobly.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg\",\"datePublished\":\"2019-03-18T12:00:33+00:00\",\"dateModified\":\"2019-04-16T11:55:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.mobly.com.br\/blog\/#\/schema\/person\/6b8770bd062932d2814750e2a12f6043\"},\"description\":\"Quer renovar a casa para a chegada da pr\u00f3xima esta\u00e7\u00e3o? A gente fez um estudo e reuniu as principais tend\u00eancias para o outono.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#primaryimage\",\"url\":\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg\",\"contentUrl\":\"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg\",\"width\":788,\"height\":526,\"caption\":\"Que tal come\u00e7ar a deixar a casa mais quentinha?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mobly.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inspira\u00e7\u00f5es\",\"item\":\"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Top 3 tend\u00eancias para o Outono 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mobly.com.br\/blog\/#website\",\"url\":\"https:\/\/www.mobly.com.br\/blog\/\",\"name\":\"Blog da Mobly\",\"description\":\"Dicas de Decora\u00e7\u00e3o, Inspira\u00e7\u00f5es e Mais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mobly.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mobly.com.br\/blog\/#\/schema\/person\/6b8770bd062932d2814750e2a12f6043\",\"name\":\"Ingrid Vilas Boas Morales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.mobly.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/44014a6de7bad71c234039b3d492ea28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/44014a6de7bad71c234039b3d492ea28?s=96&d=mm&r=g\",\"caption\":\"Ingrid Vilas Boas Morales\"},\"url\":\"https:\/\/www.mobly.com.br\/blog\/author\/ingrid-morales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top 3 tend\u00eancias para o Outono 2019 | Blog da Mobly","description":"Quer renovar a casa para a chegada da pr\u00f3xima esta\u00e7\u00e3o? A gente fez um estudo e reuniu as principais tend\u00eancias para o outono.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/","og_locale":"pt_BR","og_type":"article","og_title":"Top 3 tend\u00eancias para o Outono 2019 | Blog da Mobly","og_description":"Quer renovar a casa para a chegada da pr\u00f3xima esta\u00e7\u00e3o? A gente fez um estudo e reuniu as principais tend\u00eancias para o outono.","og_url":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/","og_site_name":"Blog da Mobly","article_published_time":"2019-03-18T12:00:33+00:00","article_modified_time":"2019-04-16T11:55:49+00:00","og_image":[{"width":788,"height":526,"url":"https:\/\/blog.mobly.com.br\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg","type":"image\/jpeg"}],"author":"Ingrid Vilas Boas Morales","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ingrid Vilas Boas Morales","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/","url":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/","name":"Top 3 tend\u00eancias para o Outono 2019 | Blog da Mobly","isPartOf":{"@id":"https:\/\/www.mobly.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg","datePublished":"2019-03-18T12:00:33+00:00","dateModified":"2019-04-16T11:55:49+00:00","author":{"@id":"https:\/\/www.mobly.com.br\/blog\/#\/schema\/person\/6b8770bd062932d2814750e2a12f6043"},"description":"Quer renovar a casa para a chegada da pr\u00f3xima esta\u00e7\u00e3o? A gente fez um estudo e reuniu as principais tend\u00eancias para o outono.","breadcrumb":{"@id":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#primaryimage","url":"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg","contentUrl":"https:\/\/www.mobly.com.br\/blog\/wp-content\/uploads\/2019\/03\/Tendencias-de-outono-abre.jpg","width":788,"height":526,"caption":"Que tal come\u00e7ar a deixar a casa mais quentinha?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/top-3-tendencias-outono-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mobly.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Inspira\u00e7\u00f5es","item":"https:\/\/www.mobly.com.br\/blog\/inspiracoes\/"},{"@type":"ListItem","position":3,"name":"Top 3 tend\u00eancias para o Outono 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.mobly.com.br\/blog\/#website","url":"https:\/\/www.mobly.com.br\/blog\/","name":"Blog da Mobly","description":"Dicas de Decora\u00e7\u00e3o, Inspira\u00e7\u00f5es e Mais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mobly.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.mobly.com.br\/blog\/#\/schema\/person\/6b8770bd062932d2814750e2a12f6043","name":"Ingrid Vilas Boas Morales","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mobly.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/44014a6de7bad71c234039b3d492ea28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44014a6de7bad71c234039b3d492ea28?s=96&d=mm&r=g","caption":"Ingrid Vilas Boas Morales"},"url":"https:\/\/www.mobly.com.br\/blog\/author\/ingrid-morales\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/posts\/4815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4815"}],"version-history":[{"count":21,"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/posts\/4815\/revisions"}],"predecessor-version":[{"id":5076,"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/posts\/4815\/revisions\/5076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/media\/4816"}],"wp:attachment":[{"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mobly.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}